{"id":14479,"date":"2020-12-07T08:45:19","date_gmt":"2020-12-07T06:45:19","guid":{"rendered":"https:\/\/againstthecompass.com\/?p=14479"},"modified":"2026-07-10T17:17:32","modified_gmt":"2026-07-10T15:17:32","slug":"ruta-kurdistan-iraqui-itinerario","status":"publish","type":"post","link":"https:\/\/againstthecompass.com\/es\/ruta-kurdistan-iraqui-itinerario\/","title":{"rendered":"Qu\u00e9 ver en el Kurdist\u00e1n iraqu\u00ed &#8211; Itinerario de 2 semanas"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/09\/kurdistan-travel-guide.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/09\/kurdistan-travel-guide.jpg\" type=\"image\/jpeg\"><img decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/09\/kurdistan-travel-guide.jpg\" alt class=\"wp-image-13840\"><\/picture><\/figure>\n\n\n\n<p>Y qu\u00e9 puedo&nbsp;decir sobre el Kurdist\u00e1n iraqu\u00ed que no haya mencionado ya?<\/p>\n\n\n\n<p>A pesar de ser una regi\u00f3n de lo m\u00e1s peque\u00f1a, localizada en <a class=\"rank-math-link\" href=\"https:\/\/againstthecompass.com\/es\/paises-oriente-medio-seguro-viajar\/\"><strong>pleno coraz\u00f3n de Oriente Medio<\/strong><\/a>, y a\u00fan perteneciendo a una pa\u00eds \u00e1rabe llamado <strong><a href=\"https:\/\/againstthecompass.com\/es\/ruta-iraq-federal\/\">Irak<\/a><\/strong> que lleva varias d\u00e9cadas en guerra, el Kurdist\u00e1n iraqu\u00ed es un pa\u00eds, o un lugar si lo prefieres, con un gran potencial tur\u00edstico, abarrotado de lugares incre\u00edbles, que van desde paisajes y monta\u00f1as fant\u00e1sticas, pueblos hist\u00f3ricos, yacimientos arqueol\u00f3gicos y aventuras de locura.<\/p>\n\n\n\n<p>Me juego lo que quieras que tras leer este art\u00edculo estar\u00e1s, no sorprendido, sino con unas ganas tremendas de empacar tu mochila para adentrarte a un pa\u00eds de lo m\u00e1s ins\u00f3lito que, de momento, en lo que va de a\u00f1os, se ha mantenido libre de guerras y terrorismo.<\/p>\n\n\n\n<p>Este art\u00edculo te muestra lugares <strong>qu\u00e9 ver en el Kurdist\u00e1n iraqu\u00ed<\/strong> en una ruta e itinerario de 2 semanas.<\/p>\n\n\n\n<div class=\"convertkit-form wp-block-convertkit-form\" style=\"\"><script async data-uid=\"6e9cfe740b\" src=\"https:\/\/exceptional-creator-2216.kit.com\/6e9cfe740b\/index.js\" data-jetpack-boost=\"ignore\" data-no-defer=\"1\" data-no-optimize=\"1\" nowprocket><\/script><\/div>\n\n\n\n<div class=\"wp-block-columns d-flex p-0 gap-0 block-announcement has-background is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\" id=\"block-announcement\" style=\"background-color:#f5f3ef\">\n<div class=\"wp-block-column block-announcement-text-side d-flex p-5 my-0 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group w-100 justify-content-between my-0 is-vertical is-nowrap is-layout-flex wp-container-core-group-is-layout-3655d5c7 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading mt-0 mb-0 has-text-color has-link-color wp-elements-756a16206276111682070df16e3e67d6\" style=\"color:#173a21;font-size:35px\">Viaja al Kurdist\u00e1n Iraq\u00ed con ATC<\/h2>\n\n\n\n<p style=\"font-size:16px\">\u00danete a la Comunidad de ATC en nuestra pr\u00f3xima expedici\u00f3n al Kurdist\u00e1n iraqu\u00ed en Nouruz<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide my-0\" style=\"background-color:#93a193;color:#93a193\"\/>\n\n\n\n<div class=\"wp-block-group my-2 is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-font-awesome-icon wp-font-awesome-icon\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"calendar\" class=\"svg-inline--fa fa-calendar \" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M152 24c0-13.3-10.7-24-24-24s-24 10.7-24 24V64H64C28.7 64 0 92.7 0 128v16 48V448c0 35.3 28.7 64 64 64H384c35.3 0 64-28.7 64-64V192 144 128c0-35.3-28.7-64-64-64H344V24c0-13.3-10.7-24-24-24s-24 10.7-24 24V64H152V24zM48 192H400V448c0 8.8-7.2 16-16 16H64c-8.8 0-16-7.2-16-16V192z\"><\/path><\/svg><\/div>\n\n\n\n<div class=\"wp-block-columns my-0 is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"m-0 has-text-color has-link-color wp-elements-d8db5fc9eceecdb15964d5cdc9f3ecc8\" style=\"color:#273b08;font-size:16px\"><strong>PR\u00d3XIMA SALIDA<\/strong><\/p>\n\n\n\n<p class=\"mt-2\" style=\"font-size:16px\">19 al 26 de mar (2027)<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group my-2 is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-font-awesome-icon wp-font-awesome-icon\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\" data-icon=\"location-dot\" class=\"svg-inline--fa fa-location-dot \" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M215.7 499.2C267 435 384 279.4 384 192C384 86 298 0 192 0S0 86 0 192c0 87.4 117 243 168.3 307.2c12.3 15.3 35.1 15.3 47.4 0zM192 128a64 64 0 1 1 0 128 64 64 0 1 1 0-128z\"><\/path><\/svg><\/div>\n\n\n\n<div class=\"wp-block-columns my-0 is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"m-0 has-text-color has-link-color wp-elements-b80117b3b4fe54a5e479d066b2c0d750\" style=\"color:#273b08;font-size:16px\"><strong>DESTACADOS<\/strong><\/p>\n\n\n\n<p class=\"mt-2\" style=\"font-size:16px\">Erbil, Sulimaniyah, Akre, Amedi, Lalish, Duhok, Mar Mattai<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons w-100 is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-098cc607 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button w-100\"><a class=\"wp-block-button__link has-atc-primary-green-background-color has-background wp-element-button\" href=\"https:\/\/expeditions.againstthecompass.com\/es\/tours\/kurdistan-nouruz\/\" style=\"border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-left-radius:8px;border-bottom-right-radius:8px\" target=\"_blank\" rel=\"noreferrer noopener\">Ver pr\u00f3ximo viaje <span class=\"wp-rich-text-font-awesome-icon wp-font-awesome-icon\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"fas\" data-icon=\"arrow-right-long\" class=\"svg-inline--fa fa-arrow-right-long \" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M502.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-128-128c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L402.7 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l370.7 0-73.4 73.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l128-128z\"><\/path><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column block-announcement-image-side m-0 is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full m-0 w-100 h-100 block-announcement-full-column-image\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"455\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2026\/06\/Screenshot-2022-09-26-at-15-53-34-kirkuk-.iraqi-forces-open-fire-against-kurds-civiles1.png\" alt=\"\" class=\"wp-image-58585\" srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2026\/06\/Screenshot-2022-09-26-at-15-53-34-kirkuk-.iraqi-forces-open-fire-against-kurds-civiles1.png 682w, https:\/\/againstthecompass.com\/wp-content\/uploads\/2026\/06\/Screenshot-2022-09-26-at-15-53-34-kirkuk-.iraqi-forces-open-fire-against-kurds-civiles1-300x200.png 300w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/que-ver-en-kurdistan.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/que-ver-en-kurdistan.jpg\" type=\"image\/jpeg\"><img decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/que-ver-en-kurdistan.jpg\" alt=\"Qu\u00e9 ver en Kurdist\u00e1n\" class=\"wp-image-14536\" style=\"object-fit:cover;width:520px;height:auto\"><\/picture><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">En esta ruta de 2 semanas por Kurdist\u00e1n encontrar\u00e1s:<\/h2>\n\n\n\n<div class=\"wp-block-group table-of-contents is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"table-of-contents__title\">\u00cdndice de contenidos<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a class=\"rank-math-link\" href=\"#1\"><span style=\"text-decoration: underline;\">Razones por las que visitar<\/span><\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#3\"><span style=\"text-decoration: underline;\">Itinerario<\/span><\/a>\n<ul class=\"wp-block-list\">\n<li><a class=\"rank-math-link\" href=\"#6\"><span style=\"text-decoration: underline;\">D\u00eda 1, 2 &#8211; Erbil<\/span><\/a><\/li>\n\n\n\n<li><a href=\"#7\" class=\"rank-math-link\"><span style=\"text-decoration: underline;\">D\u00eda 3 &#8211; Campo de refugiados sirio<\/span><\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#8\"><span style=\"text-decoration: underline;\">D\u00eda 4, 5 &#8211; Sulaymaniyah<\/span><\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#9\"><span style=\"text-decoration: underline;\">D\u00eda 6 &#8211; Halabja &amp; Ahmadawa<\/span><\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#10\"><span style=\"text-decoration: underline;\">D\u00eda 7, 8 &#8211; Aqrah<\/span><\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#11\"><span style=\"text-decoration: underline;\">D\u00eda 9, 10 &#8211; Soran &amp; Rawandiz<\/span><\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#12\"><span style=\"text-decoration: underline;\">D\u00eda 11, 12 &#8211; Amadiya<\/span><\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#13\"><span style=\"text-decoration: underline;\">D\u00eda 13, 14 &#8211; Dohuk<\/span><\/a><\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#14\"><span style=\"text-decoration: underline;\">D\u00eda 15 &#8211; Lalish<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><a class=\"rank-math-link\" href=\"#4\"><span style=\"text-decoration: underline;\">M\u00e1s informaci\u00f3n<\/span><\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-group atc-info-box is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading has-text-align-center m-0 has-black-color has-text-color has-background\" style=\"background-color:#fe9900\">El seguro de viajes que recomendamos para Irak<\/h4>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:20px\"><strong><a href=\"https:\/\/www.iatiseguros.com\/?r=30867932099453&amp;cmp=iraqi_kurdistan_itinerary_es_text\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\">IATI Seguros<\/a><\/strong> es una de las pocas que cubre viajar en Irak.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-black-color has-text-color has-background has-link-color has-text-align-center has-custom-font-size wp-element-button\" href=\"https:\/\/www.iatiseguros.com\/?r=30867932099453&amp;cmp=iraqi_kurdistan_itinerary_es_text\" style=\"border-radius:11px;background-color:#fe9900;font-size:16px\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\">5% DE DESCUENTO AQU\u00cd<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1\">Deber\u00edas ir al Kurdist\u00e1n?<\/h2>\n\n\n\n<p>No hay semana en la que en mi bandeja de entrada no me aparezcan como un m\u00ednimo un par o tres de emails de viajeros quienes, ansiosos, se mueren por ir el Kurdist\u00e1n, aunque sin embargo, no pueden evitar mostrarse esc\u00e9pticos en cuanto a la seguridad, es decir, que les da un poco de miedo.<\/p>\n\n\n\n<p>Es perfectamente comprensible.<\/p>\n\n\n\n<p>A m\u00ed tambi\u00e9n me daba miedo la primera vez que fui en el 2016, pero cuando volv\u00ed en el 2018, despu\u00e9s de tener m\u00e1s conocimientos sobre la regi\u00f3n, estuve la mar de tranquilo y hasta te dir\u00e9 que estuve mucho m\u00e1s preocupado por mi seguridad cuando viaj\u00e9 a M\u00e9xico en enero del 2018, que cuando estuve haciendo autoestop y acampando por el Kurdist\u00e1n.<\/p>\n\n\n\n<p>Kurdist\u00e1n es una regi\u00f3n digamos vol\u00e1til pero como m\u00ednimo, en lo que va de a\u00f1os, se ha mantenido perfectamente segura. Si quieres saber m\u00e1s, lee: <strong><a href=\"https:\/\/againstthecompass.com\/es\/es-seguro-viajar-a-iraq\/\">Es seguro viajar a Irak?<\/a><\/strong><\/p>\n\n\n\n<p>Por otra parte, independientemente de la seguridad, Kurdist\u00e1n puede que no sea un pa\u00eds para todo el mundo. Deber\u00edas saber que la infraestructura tur\u00edstica est\u00e1 bastante limitada y que aunque no nos guste, es una zona altamente militarizada, con un sinf\u00edn de controles y restricciones espor\u00e1dicas, as\u00ed porque s\u00ed, a extranjeros.<\/p>\n\n\n\n<p>Durante mi viaje, fui una vez arrestado por los peshmergas, en una ocasi\u00f3n me vi forzado a acampar a las afueras de una ciudad porque no encontr\u00e9 ning\u00fan hotel y, la mitad de las veces tuve que hacer autoestop porque no hab\u00eda transporte p\u00fablico y los taxis de all\u00ed te cobran un buen past\u00f3n.<\/p>\n\n\n\n<p>Sinceramente, no es tanto como parece, ni tan salvaje como <strong><a href=\"https:\/\/againstthecompass.com\/es\/country\/pakistan\/\">Pakist\u00e1n<\/a><\/strong> o Afganist\u00e1n, aunque ten en cuenta que puede que pases por alguna que otra aventura un tanto selv\u00e1tica.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14518\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/canyon-rawanduz.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/canyon-rawanduz.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/canyon-rawanduz.jpg\" alt=\"Ca\u00f1\u00f3n de Rawandiz\" class=\"wp-image-14518\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>Ca\u00f1\u00f3n de Rawandiz, cerca de Sor\u00e1n<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"3\">Qu\u00e9 ver en Kurdist\u00e1n &#8211; Ruta e itinerario de 2 semanas<\/h2>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#e8e8e8\">Lee mi experiencia <a href=\"https:\/\/againstthecompass.com\/es\/visita-mosul-tras-liberacion\/\"><strong>visitando Mosul en Irak<\/strong><\/a><\/p>\n\n\n\n<p>Yo <strong><a href=\"https:\/\/againstthecompass.com\/es\/frontera-iran-irak\/\">cruc\u00e9 a Irak por tierra desde Ir\u00e1n<\/a><\/strong>, por lo que mi viaje empez\u00f3 en Suleymaniyah.<\/p>\n\n\n\n<p>Sin embargo, vamos a asumir que tu viaje empieza en Erbil, que ser\u00eda lo m\u00e1s probable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-vivid-red-color has-text-color\"><span style=\"text-decoration: underline;\">Mapa de la ruta de 2 semanas por Kurdist\u00e1n<\/span><\/h3>\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1bMCQLBO6dwo87s_bluoQs2cl_bKAub1y&#038;ehbc=2E312F\" width=\"640\" height=\"480\"><\/iframe>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"6\">D\u00eda 1, 2 &#8211; Erbil<\/h3>\n\n\n\n<p>Erbil es la capital del Kurdist\u00e1n iraqu\u00ed y se convertir\u00eda en la capital de todo Kurdist\u00e1n, incluyendo en Turqu\u00eda, <a href=\"https:\/\/againstthecompass.com\/es\/viajar-siria\/\" class=\"rank-math-link\"><strong>Siria<\/strong><\/a> e Ir\u00e1n, si \u00e9ste se convirtiese jam\u00e1s en un estado independiente.<\/p>\n\n\n\n<p>Considerada una de las ciudades m\u00e1s antiguas del mundo, los expertos especulan que los primeros restos de civilizaci\u00f3n provienen del siglo 28 A.C. Casi nada.<\/p>\n\n\n\n<p>A d\u00eda de hoy, Erbil es una ciudad pro-occidental, bastante moderna por cierto, y con montones de cosas qu\u00e9 ver, desde la ciudadela, considerada Patrimonio de la UNESCO, hasta el distrito cristiano de Ankawa y mogoll\u00f3n de bazares y salones de t\u00e9 de lo m\u00e1s \u00e9picos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Qu\u00e9 ver en Erbil<\/h4>\n\n\n\n<p>Te invito a que leas mi gu\u00eda de <strong><a href=\"https:\/\/againstthecompass.com\/es\/10-cosas-que-hacer-en-erbil-iraq\/\">cosas qu\u00e9 ver en Erbil<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-13459\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/09\/erbil-travel.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/09\/erbil-travel.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/09\/erbil-travel.jpg\" alt class=\"wp-image-13459\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>La plaza mayor de Erbil<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\">D\u00f3nde alojarse en Erbil<\/h4>\n\n\n\n<p class=\"has-medium-font-size\"><strong>S\u00faper econ\u00f3mico \u2013&nbsp;<\/strong><span style=\"text-decoration: underline;\">Layli Baghdad<\/span><strong> \u2013&nbsp;<\/strong>El hotel m\u00e1s barato de Erbil cobra la habitaci\u00f3n privada a 15,000ID. No se puede reservar online, pero est\u00e1 en la calle Bata, en la parte oeste del bazar. Localizaci\u00f3n:&nbsp;<em>36.188962,44.007374<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Hotel econ\u00f3mico \u2013&nbsp;<\/strong><span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.booking.com\/hotel\/iq\/osso-o-uu-osso-o-uu1.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\">Fareeq<\/a><\/strong><\/span>&nbsp;\u2013 No tan barato, pero mucho mejor y adem\u00e1s se puede reservar online. Una de las opciones econ\u00f3micas mejor valoradas de Erbil.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.booking.com\/hotel\/iq\/osso-o-uu-osso-o-uu1.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" style=\"border-radius:11px;background-color:#0c3b7c\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><strong>M\u00edralo en Booking.com<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Presupuesto medio \u2013<\/strong>&nbsp;<span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.booking.com\/hotel\/iq\/erbil-view.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\">Erbil View Hotel<\/a><\/strong><\/span>&nbsp;\u2013 El hotel mejor puntuado de la ciudad, con un personal de lo m\u00e1s y un s\u00faper desayuno.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.booking.com\/hotel\/iq\/erbil-view.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" style=\"border-radius:11px;background-color:#0c3b7c\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><strong>M\u00edralo en Booking.com<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14502\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/kurds-iraq.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/kurds-iraq.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/kurds-iraq.jpg\" alt=\"Kurdos Irak\" class=\"wp-image-14502\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>Un kurdo de Erbil<\/em><\/span><\/figcaption><\/figure>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"7\">D\u00eda 3 &#8211; Visita un campo de refugiados en Irak<\/h3>\n\n\n\n<p>Una de las <a href=\"https:\/\/againstthecompass.com\/es\/category\/historias-inspiradoras\/\" class=\"rank-math-link\"><strong>experiencias viajeras<\/strong><\/a> m\u00e1s gratificantes que jam\u00e1s he vivido, por no decir la mejor, fue visitar un campo de refugiados en Irak.<\/p>\n\n\n\n<p>Ser capaz de aportar mi granito de arena a ayudar a aquellas personas que directamente est\u00e1n sufriendo la peor crisis humanitaria del siglo XXI fue realmente incre\u00edble, hasta tal punto que me resulta dif\u00edcil poder explicarlo con palabras.<\/p>\n\n\n\n<p>Me levant\u00e9 temprano por la ma\u00f1ana y me fui al bazar a comprar y llenar un par de sacos a petar de juguetes, con el fin de repartirlos entre tantos ni\u00f1os como pude.<\/p>\n\n\n\n<p>Me qued\u00e9 sin juguetes en cuesti\u00f3n de minutos y os lo digo, fue muy, pero que muy bonito&#8230;<\/p>\n\n\n\n<p>Como imaginar\u00e1s, hay montones de campos por toda la regi\u00f3n, pero yo fui al de Darashakran, ya que no requiere de permiso alguno.<\/p>\n\n\n\n<p>Esto fue en 2016, pero cuando volv\u00ed en 2018, tambi\u00e9n intent\u00e9 visitar el campo de Aqrah, aunque desafortunadamente, me ped\u00edan un permiso especial, as\u00ed que no pude entrar.<\/p>\n\n\n\n<p>En fin, por si te animas, aqu\u00ed tienes mi historia completa: <strong><a href=\"https:\/\/againstthecompass.com\/es\/campo-de-refugiados-sirio-iraq\/\">Visitando un campo de refugiados sirio en Irak<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-2986 size-full\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2016\/10\/me-toys-children-syrian.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2016\/10\/me-toys-children-syrian.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2016\/10\/me-toys-children-syrian.jpg\" alt class=\"wp-image-2986\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"color: #808080;\"><em><span style=\"font-size: 10pt;\">en el campo de refugiados<\/span><\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo llegar a Darashakran desde Erbil<\/h4>\n\n\n\n<p>Como puedes ver en el mapa de m\u00e1s arriba, Darashakran se encuentra a 45km al norte de Erbil. S\u00f3lo se puede llegar en coche.<\/p>\n\n\n\n<p>Podr\u00edas intentar ir en taxi, aunque yo personalmente no lo har\u00eda, b\u00e1sicamente porque es aconsejable ir con alg\u00fan amigo local, ya que esta persona tendr\u00e1 que hablar con los militares que custodian la entrada del campo, y dudo mucho que el primer taxista que te encuentres sepa muy bien de qu\u00e9 va la historia.<\/p>\n\n\n\n<p>Intenta encontrar a alg\u00fan amigo que hable ingl\u00e9s y sino, busca alg\u00fan gu\u00eda. Puedes preguntar en el hotel o en Couchsurfing.<\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#f2f2f2\">Lee: <strong><a class=\"rank-math-link\" href=\"https:\/\/againstthecompass.com\/es\/que-ver-iran-itinerario\/\">De ruta por Ir\u00e1n: Itinerario de 1 a 4 semanas<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-7338 size-full\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2016\/10\/darashakran.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2016\/10\/darashakran.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2016\/10\/darashakran.jpg\" alt class=\"wp-image-7338\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"color: #808080;\"><em><span style=\"font-size: 10pt;\">Darashakran<\/span><\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"8\">D\u00eda 4, 5 &#8211; Sulaymaniyah<\/h3>\n\n\n\n<p>Si Erbil te pareci\u00f3 una ciudad moderna y abierta, sobretodo despu\u00e9s de haber paseado por Ankawa, \u00fanicamente para recorrerte todas las licorer\u00edas, iglesias y ver a montones de expatriados, entonces estate preparado para cuando llegues a Sulaymaniyah, porque esta es la ciudad m\u00e1s occidentalizada de Kurdist\u00e1n y, como no, de Irak.<\/p>\n\n\n\n<p>A pesar de ser una ciudad musulmana sun\u00ed, ver\u00e1s que muchas mujeres no traen el <em>hijab<\/em> puesto, pero lo que me sorprendi\u00f3 m\u00e1s fue el hecho que en todos los bares siempre hab\u00eda grupos mixtos de hombres y mujeres, un escenario de lo m\u00e1s in\u00e9dito en Oriente Medio.<\/p>\n\n\n\n<p>Por cierto, ver\u00e1s que todo el mundo pronuncia y escribe el nombre de la ciudad de manera diferente:&nbsp;Sulaymaniyah, Slemani, Suli, As Sulaymaniyah, Sulemani, etc. No me preguntes por qu\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14508\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180414_112626.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180414_112626.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180414_112626.jpg\" alt class=\"wp-image-14508\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>Red Security Museum &#8211; Las celdas<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Qu\u00e9 ver en Sulaymaniyah<\/h4>\n\n\n\n<p><strong>Red Security Museum (Amna Suraka) &#8211;<\/strong>&nbsp;De visita obligatoria. B\u00e1sicamente, esta es la Casa de los Horrores de Sadam Hussein y que muestra el genocidio que su r\u00e9gimen llev\u00f3 a cabo contra la poblaci\u00f3n kurda cuando invadieron el Kurdist\u00e1n. <\/p>\n\n\n\n<p>El museo se encuentra en el mismo edificio que sol\u00eda ejercer de oficinas centrales para el r\u00e9gimen y en \u00e9l encuentras todav\u00eda algunos de sus tanques y armamento, as\u00ed como las celdas en donde ten\u00edan encerrados a los kurdos. Adem\u00e1s, acaban de tambi\u00e9n abrir una secci\u00f3n dedicada al Estado Isl\u00e1mico. <\/p>\n\n\n\n<p><strong>El bazar &#8211;<\/strong> Tampoco puedes perd\u00e9rtelo.<\/p>\n\n\n\n<p><strong>Monte Goyzha &#8211;<\/strong>&nbsp;Un lugar muy frecuentado por los locales que no es nada menos que un mirador de las vistas de la ciudad.<\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#f2f2f2\">Lee: <strong><a href=\"https:\/\/againstthecompass.com\/es\/viajar-kurdistan-iraqui-mujer\/\">C\u00f3mo es viajar al Kurdist\u00e1n siendo mujer<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14514\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/DSC_4447.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/DSC_4447.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/DSC_4447.jpg\" alt class=\"wp-image-14514\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>Kurdos en el bazar de Sulaymaniyah<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\">D\u00f3nde alojarse en Sulaymaniyah<\/h4>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Hostel mochileros<\/strong> &#8211; <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/hostelworld.prf.hn\/click\/camref:1100l36N5\/pubref:iraqi_kurdistan_itinerary_es\/destination:https%3A%2F%2Fwww.spanish.hostelworld.com%2Fhosteldetails.php%2FDolphin-Hotel-and-Hostel-Sulaymaniyah%2FSuleymaniyah%2F91319%3F\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\">Dolphin<\/a><\/strong><\/span> &#8211; El \u00fanico hostel de todo Irak est\u00e1 en Sulaymaniyah. Dispone de buen Wi-Fi y adem\u00e1s, el propietario organiza distintos tours y actividades.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/hostelworld.prf.hn\/click\/camref:1100l36N5\/pubref:iraqi_kurdistan_itinerary_es\/destination:https%3A%2F%2Fwww.spanish.hostelworld.com%2Fhosteldetails.php%2FDolphin-Hotel-and-Hostel-Sulaymaniyah%2FSuleymaniyah%2F91319%3F\" style=\"border-radius:11px;background-color:#fe7549\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><strong>M\u00edralo en Hostelworld<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Un poco mejor &#8211;<\/strong> <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.booking.com\/hotel\/iq\/khan-saray.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\">Khan Saray<\/a><\/strong><\/span> &#8211; La mejor opci\u00f3n de presupuesto medio de la ciudad. Buena ubicaci\u00f3n e instalaciones&nbsp; y una muy buena relaci\u00f3n calidad-precio.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.booking.com\/hotel\/iq\/khan-saray.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" style=\"border-radius:11px;background-color:#0c3b7c\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><strong>M\u00edralo en Booking.com<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Lujo &#8211;<\/strong>&nbsp;<span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.booking.com\/hotel\/iq\/ramada-sulaymaniyah.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\">Hotel&nbsp;Ramadan<\/a><\/strong><\/span>&nbsp;&#8211; Por lo que se ve, este fue el primer hotel de 5 estrellas jam\u00e1s inaugurado en Irak y, a d\u00eda de hoy, el mejor de Sulaymaniyah.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.booking.com\/hotel\/iq\/ramada-sulaymaniyah.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" style=\"border-radius:11px;background-color:#0c3b7c\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><strong>M\u00edralo en Booking.com<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo llegar a Sulaymaniyah desde Erbil<\/h4>\n\n\n\n<p>A pesar de estar relativamente cerca, todos los autobuses y taxis toman la ruta larga, b\u00e1sicamente porque la r\u00e1pida pasa por Kirkuk, una ciudad no muy segura seg\u00fan dicen y que de todas formas, los turistas no pueden ir.<\/p>\n\n\n\n<p>La ruta larga toma unas 3 o 4 horas.<\/p>\n\n\n\n<p><strong>Taxis locales compartidos &#8211;<\/strong>&nbsp;Cuestan 15,000ID (12.50USD)<\/p>\n\n\n\n<p><strong>Mini-furgonetas &#8211;<\/strong>&nbsp;Cuestan 10,000ID (8.40USD)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14498\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/red-security-museum-sulaymaniyah.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/red-security-museum-sulaymaniyah.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/red-security-museum-sulaymaniyah.jpg\" alt class=\"wp-image-14498\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>Los tanques de Sadam y las oficinas centrales de su r\u00e9gimen<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<div class=\"convertkit-form wp-block-convertkit-form\" style=\"\"><script async data-uid=\"6e9cfe740b\" src=\"https:\/\/exceptional-creator-2216.kit.com\/6e9cfe740b\/index.js\" data-jetpack-boost=\"ignore\" data-no-defer=\"1\" data-no-optimize=\"1\" nowprocket><\/script><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"9\">D\u00eda 6 &#8211; Halabja y Ahmadawa<\/h3>\n\n\n\n<p>Halabja y Ahmadawa se encuentran en el distrito de Sulaymaniyah y ambos pueden visitarse en un viajecito de un d\u00eda, a\u00fan yendo en transporte p\u00fablico.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Halabja<\/h4>\n\n\n\n<p>En 1988, durante la <strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/Guerra_Ir%C3%A1n-Irak\" target=\"_blank\" rel=\"noreferrer noopener\">guerra de Ir\u00e1n e Irak<\/a><\/strong>, los iran\u00edes se apoderaron de un peque\u00f1o pueblo llamado Halabja.<\/p>\n\n\n\n<p>Como consecuencia, en respuesta a la invasi\u00f3n, el r\u00e9gimen de Sadam Hussein lanz\u00f3 un ataque masivo mediante el uso de armas qu\u00edmicas que acabaron con la vida de miles de personas en cuesti\u00f3n de segundos, en su mayor\u00eda kurdos locales.<\/p>\n\n\n\n<p>El ataque fue condenado por muchos tribunales de alrededor del mundo, quienes lo calificaron como un crimen contra la humanidad y un verdadero genocidio.<\/p>\n\n\n\n<p>A d\u00eda de hoy, Halabja no es m\u00e1s que un pueblo normal y corriente donde encuentras un memorial en favor de las v\u00edctimas y un museo, que vendr\u00eda a ser como el Casa de los Horrores de Sadam Hussein Parte 2.<\/p>\n\n\n\n<p>El museo est\u00e1 en la entrada de la ciudad y abre de 9 a 12h y de 15 a 17h.<\/p>\n\n\n\n<p><strong>C\u00f3mo llegar a Halabja &#8211;<\/strong> Desde la terminal de Suli, los taxis locales cuestan 6,000ID (5USD) por persona.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14512\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/halabja-memorial.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/halabja-memorial.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/halabja-memorial.jpg\" alt class=\"wp-image-14512\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>El memorial que representa a las v\u00edctimas<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Ahmadawa<\/h4>\n\n\n\n<p>Ahmadawa es un pueblo monta\u00f1oso y un destino tur\u00edstico muy t\u00edpico entre los locales. Est\u00e1 a unos 30km de Halabja y creo que la mejor manera de llegar es haciendo autoestop, aunque probablemente tengas que hacer un par o tres de paradas.<\/p>\n\n\n\n<p>La principal atracci\u00f3n de Ahmadawa es una cascada que est\u00e1 a un par o tres kil\u00f3metros del pueblo, cuyo sendero pasa por mogoll\u00f3n de tiendecitas, cafecitos y dem\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14528\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/ahmadawa.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/ahmadawa.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/ahmadawa.jpg\" alt class=\"wp-image-14528\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>Ahmadawa<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo volver a Sulaymaniyah <\/h4>\n\n\n\n<p>Tendr\u00e1s primero que hacer autoestop hasta un pueblo llamado Khurmal, a 3km antes de Ahmadawa. All\u00ed hay una peque\u00f1a estaci\u00f3n de taxis, aunque a partir de las 4 o 5 de la tarde, puede que ya no haya taxis que vayan directos a Sulaymaniyah. As\u00ed pues, lo que hice fue coger un taxi compartido hasta Sadiq Siad (2,000ID) y desde all\u00ed, pagu\u00e9 3,000ID para uno directo a Suli.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14510\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/halabja-museum.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/halabja-museum.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/halabja-museum.jpg\" alt class=\"wp-image-14510\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>El museo de Halabja<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"10\">D\u00eda 7, 8 &#8211; Aqrah<\/h3>\n\n\n\n<p>Rodeado de una preciosa naturaleza y compuesto por un casco antiguo de lo m\u00e1s bonito, Aqrah (o Akre) es un pueblo muy fotog\u00e9nico y uno de los mejores lugares qu\u00e9 visitar en el Kurdist\u00e1n iraqu\u00ed.<\/p>\n\n\n\n<p>Su historia es un tanto incierta y la verdad es que nunca encontr\u00e9 demasiada informaci\u00f3n, pero es un pueblo agradable por el que pasear y conocer a gente local.<\/p>\n\n\n\n<p>De hecho, all\u00ed conoc\u00ed a un hombre muy interesante de unos 50 y pico a\u00f1os que hab\u00eda vivido en Austria por no s\u00e9 cu\u00e1ntos a\u00f1os, pero que se vio forzado a volver al Kurdist\u00e1n, y es que Sadam Hussein lo amenaz\u00f3 con matar a su familia si \u00e9ste no volv\u00eda. <\/p>\n\n\n\n<p>Tambi\u00e9n me cont\u00f3 la triste historia de c\u00f3mo su hermano hab\u00eda sido recientemente asesinado a sangre fr\u00eda por el Estado Isl\u00e1mico <a href=\"https:\/\/againstthecompass.com\/es\/visita-mosul-tras-liberacion\/\"><strong>en Mosul<\/strong><\/a>, con el \u00fanico fin de vengarse de que Ramzi trabajaba de int\u00e9rprete por el ej\u00e9rcito americano. Si quieres saber m\u00e1s sobre \u00e9l, <\/p>\n\n\n\n<p>Ramzi es un t\u00edo muy carism\u00e1tico con historias interesantes que contar, aunque le dejan a uno de piedra. Adem\u00e1s, trabaja como gu\u00eda de la zona, as\u00ed que si quieres que te cuente y te ense\u00f1e un poco, puedes contactarlo a&nbsp;+9647507560154.<\/p>\n\n\n\n<p>No estoy seguro de si acordar\u00e1 de m\u00ed, pero le puedes decir mi nombre y nacionalidad, sin ning\u00fan problema. Lo conoc\u00ed en abril del 2018 y soy el chico a quien echaron de la caso del director del campo de refugiados sin raz\u00f3n alguna. Si le cuentas esto, es probable que me recuerde.<\/p>\n\n\n\n<p>En Aqrah, no hice m\u00e1s que caminar por el casco antiguo y pasar el rato con Ramzi.<\/p>\n\n\n\n<p>Si lo prefieres, tambi\u00e9n se puede hacer trekking, incluyendo una caminata de un par de horas a un monasterio cristiano muy antiguo.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-14526 size-full\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/akre-kurdistan.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/akre-kurdistan.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/akre-kurdistan.jpg\" alt class=\"wp-image-14526\"><\/picture><figcaption class=\"wp-element-caption\"><em><span style=\"font-size: 10pt; color: #808080;\">Aqrah<\/span><\/em><\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00f3nde alojarse en Aqrah<\/h4>\n\n\n\n<p>Yo no me qued\u00e9 en ning\u00fan hotel, sino que acamp\u00e9 a las afueras de la ciudad. Los locales me hab\u00edan hablado de dos hoteles que tambi\u00e9n aparec\u00edan en <strong><a rel=\"noreferrer noopener\" class=\"rank-math-link\" href=\"https:\/\/maps.me\/\" target=\"_blank\">map<\/a><a href=\"https:\/\/maps.me\/\" target=\"_blank\" aria-label=\"s (opens in a new tab)\" rel=\"noreferrer noopener nofollow\" class=\"rank-math-link\">s<\/a><a rel=\"noreferrer noopener\" class=\"rank-math-link\" href=\"https:\/\/maps.me\/\" target=\"_blank\">.me<\/a><\/strong>, pero por alguna raz\u00f3n, estaban cerrados.<\/p>\n\n\n\n<p>Despu\u00e9s me mencionaron un tercer hotel llamado Azadi que seg\u00fan ellos estaba abierto al 100%, pero estaba demasiado lejos y ya era tarde, as\u00ed que me decid\u00ed plantar mi tienda en frente de un s\u00faper y me march\u00e9 bien temprano por la ma\u00f1ana. El <strong>Hotel Azadi<\/strong> est\u00e1 justo al lado del campo de refugiados de Aqrah. Aqu\u00ed:&nbsp;<em>36.73196, 43.869507<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo llegar a Aqrah<\/h4>\n\n\n\n<p>Si est\u00e1s en Suli, deber\u00e1s ir primero a Erbil y, desde Erbil, hay taxis locales que cobran 10,000ID (8.40USD) por persona. Por cierto, la carretera de Erbil a Aqrah pasa por el campo de refugiados de Darashakran y de hecho, nos paramos all\u00ed para recoger un <em>pershmerga<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-14520 size-full\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/aqrah-kurdistan.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/aqrah-kurdistan.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/aqrah-kurdistan.jpg\" alt class=\"wp-image-14520\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"color: #808080;\"><em><span style=\"font-size: 10pt;\">Aqrah<\/span><\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"11\">D\u00eda 9, 10 &#8211; Soran y Rawandiz<\/h3>\n\n\n\n<p>Hogar de los paisajes y monta\u00f1as m\u00e1s incre\u00edbles del pa\u00eds, Soran es un pueblo relativamente grande, de poco inter\u00e9s en mi opini\u00f3n, pero la base para llegar a Rawandiz, un peque\u00f1o pueblecito construido en el borde de un impresionante acantilado y que forma un ca\u00f1\u00f3n todav\u00eda m\u00e1s impresionante.<\/p>\n\n\n\n<p>Rawandiz es realmente impresionante, como ning\u00fan otro lugar que hayas estado en la regi\u00f3n.<\/p>\n\n\n\n<p>Una vez llegues a Soran, tienes que dirigirte r\u00e1pidamente a Rawandiz, que est\u00e1 a unos 7km. Puedes hacer autoestop o pagar los 5,000ID que cuesta un taxi.<\/p>\n\n\n\n<p>Cuando llegues al pueblo, despu\u00e9s de haberlo visitado, dir\u00edgete al borde del acantilado. A continuaci\u00f3n, sal del pueblo en direcci\u00f3n opuesta a Soran, hacia la cascada de Bekhal. Tendr\u00e1s que hacer autoestop porque queda lejos. <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/rawandiz-canyon.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/rawandiz-canyon.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/rawandiz-canyon.jpg\" alt class=\"wp-image-14500\"><\/picture><figcaption class=\"wp-element-caption\">Rawandiz<\/figcaption><\/figure>\n\n\n\n<p>La cascada est\u00e1 bien, pero si contin\u00faas caminando por un kil\u00f3metro m\u00e1s, te encontrar\u00e1s con una peque\u00f1a tienda de cerveza, as\u00ed en medio de la nada, y desde donde se divisan una de las mejores perspectivas del ca\u00f1\u00f3n.<\/p>\n\n\n\n<p>Tambi\u00e9n recomiendo seguir caminando por la carretera durante un par o tres de kil\u00f3metros m\u00e1s, m\u00e1s que nada para ver diferentes vistas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00f3nde alojarse en Soran<\/h4>\n\n\n\n<p>En Rawandiz no hay nada m\u00e1s que resorts y hoteles caros, pero en Soran, hay un hotel baratito llamado <strong>Zagros Hotel<\/strong>, muy cerca del centro y de la rotonda principal. Es un hotel decente y ped\u00edan 20,000ID, aunque consegu\u00ed rebajarlo a 15,000ID. Esta es la ubicaci\u00f3n: <em>36.654925, 44.539426<\/em>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo llegar a Soran<\/h4>\n\n\n\n<p>Desde Aqrah, los taxis cobran 10,000ID por persona.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-14542 size-full\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/DSC_4695.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/DSC_4695.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/DSC_4695.jpg\" alt class=\"wp-image-14542\"><\/picture><figcaption class=\"wp-element-caption\">La carretera de Hamilton<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"12\">D\u00eda 11, 12 &#8211; Amadiya<\/h3>\n\n\n\n<p>Amadiya (o Amedi) es mi lugar favorito del Kurdist\u00e1n iraqu\u00ed.<\/p>\n\n\n\n<p>B\u00e1sicamente, es una aldea de m\u00e1s de 5,000 a\u00f1os de antig\u00fcedad localizada en lo alto de una monta\u00f1a, muy bonita, y que su antigua entrada de pierda sigue todav\u00eda intacta.<\/p>\n\n\n\n<p>Amedi es muy peque\u00f1o pero te digo que ofrece entretenimiento para rato. Por ejemplo, puedes subirte a alguno de los picos de los alrededores, m\u00e1s que nada para poder divisar la aldea desde arriba. De lo contrario, nunca podr\u00e1s llegar a apreciar su forma.<\/p>\n\n\n\n<p>La aldea ha sido habitada por muchas civilizaciones, desde asirios hasta persas, jud\u00edos y cristianos. A d\u00eda de hoy, es predominantemente sun\u00ed, aunque tambi\u00e9n viven algunos cristianos, ya que hay una licorer\u00eda en el mismo centro.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n, lee mi <strong><a href=\"https:\/\/againstthecompass.com\/es\/viaje-amadiya-increible-kurdistan-iraqui\/\">gu\u00eda para visitar Amadiya<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-14524 size-full\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/amadiya-gate.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/amadiya-gate.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/amadiya-gate.jpg\" alt=\"Amadiya gate\" class=\"wp-image-14524\"><\/picture><figcaption class=\"wp-element-caption\"><em><span style=\"font-size: 10pt; color: #808080;\">Antigua puerta de Amedi<\/span><\/em><\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00f3nde alojarse en Amadiya<\/h4>\n\n\n\n<p>Dentro del pueblo no hay ning\u00fan hotel, sino que est\u00e1n todos en las afueras, como a un par o tres de kil\u00f3metros.<\/p>\n\n\n\n<p>De hecho, le pregunt\u00e9 a un hombre si hab\u00eda alg\u00fan hostal o guesthouse as\u00ed baratito y me dijo que me pod\u00eda quedar en la mezquita, y es que dicen que la mezquita siempre acoge a visitantes.<\/p>\n\n\n\n<p>Me fui a la mezquita, donde me dijeron que me pod\u00eda tumbar all\u00ed en un riconcito encima de la alfombra, sin problema. Sin embargo, cuando ya ten\u00eda todo mi campamento montado, se me acercaron unos estudiantes para decirme que pod\u00eda quedarme en su casa. Cojonudo.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-14522 size-full\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/amadiya-1.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/amadiya-1.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/amadiya-1.jpg\" alt class=\"wp-image-14522\"><\/picture><figcaption class=\"wp-element-caption\"><em><span style=\"font-size: 10pt; color: #808080;\">Amedi desde el aire<\/span><\/em><\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo llegar a Amadiya<\/h4>\n\n\n\n<p>Yo vine desde Soran, que est\u00e1 a unos 170km siguiendo una la carretera que transcurre por la monta\u00f1a.<\/p>\n\n\n\n<p>No hab\u00eda transporte p\u00fablico y seg\u00fan un kurdo de Soran, deber\u00eda tomar primero un taxi hasta Dohuk y, desde all\u00ed, un segundo taxi hacia Amadiya, lo cual hubiese implicado tomar un ruta muy larga y cara.<\/p>\n\n\n\n<p>As\u00ed pues, me hice los 170km enteritos en autoestop, lo cual me llev\u00f3 el d\u00eda entero, b\u00e1sicamente porque la carretera transcurre por montones de pueblecitos, as\u00ed que tuve que subirme como en 10 coches distintos, pero por suerte, llegu\u00e9 a Amadiya justo antes de la puesta de sol.<\/p>\n\n\n\n<p>Por cierto, de camino a Amadiya (si vienes desde Soran), hay un pueblo llamado <strong>Barzan<\/strong>, el pueblo natal de <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/es.wikipedia.org\/wiki\/Mustafa_Barzani\" target=\"_blank\">Mustafa Barzani<\/a><\/strong>, un h\u00e9roe nacional y uno de los pol\u00edticos m\u00e1s destacados del Kurdist\u00e1n. <\/p>\n\n\n\n<p>En Barzan se encuentra su tumba y un memorial en su honor (muri\u00f3 en 1979). Tuve mucha suerte de que una de las familias con quienes hice autoestop quisieron parar all\u00ed para comer.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14540\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180420_123750.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180420_123750.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180420_123750.jpg\" alt class=\"wp-image-14540\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>En Barzan con la familia con quien hice autoestop<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"13\">D\u00eda 13, 14 &#8211; Dohuk<\/h3>\n\n\n\n<p>Dohuk es la tercera ciudad del Kurdist\u00e1n y un punto de tr\u00e1nsito para la gente que va o viene de Turqu\u00eda.<\/p>\n\n\n\n<p>Para m\u00ed Dohuk es bastante aburrido, sobretodo si esta es tu \u00faltimo destino del Kurdist\u00e1n. No hice demasiado, salvo descansar, pero es que tampoco hay mucho qu\u00e9 hacer, a parte de visitar el bazar, pero despu\u00e9s de haber visitado cientos de bazares <a href=\"https:\/\/againstthecompass.com\/es\/por-que-no-deberias-visitar-todos-los-paises-del-mundo\/\"><strong>por todo el mundo<\/strong><\/a>, pues que quieres qu\u00e9 te diga.<\/p>\n\n\n\n<p>Tambi\u00e9n hay un r\u00edo que si lo sigues te lleva a una presa y un lago artificial, la principal atracci\u00f3n de la ciudad. De nuevo, pues que quieres qu\u00e9 te diga.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/dohuk-kurdistan.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/dohuk-kurdistan.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/dohuk-kurdistan.jpg\" alt class=\"wp-image-14516\"><\/picture><figcaption class=\"wp-element-caption\">Centro de Dohuk<\/figcaption><\/figure>\n\n\n\n<p>Por cierto, de camino a Amadiya y Dohuk, te aconsejo que te pares a la <strong>casa de verano de Sadam Hussein<\/strong>, que est\u00e1 en la cima de una monta\u00f1a desde donde observas magn\u00edficas vistas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo llegar a la casa de Sadam Hussein <\/h4>\n\n\n\n<p>Primero, deber\u00e1s ir a Sarsang, una peque\u00f1a aldea que est\u00e1 justo entre Dohuk y Amadiya. Desde aqu\u00ed, se puede tomar una carretera de 14km que te lleva directo a la casa. No hay transporte p\u00fablico y un taxi de ida y vuelta me pareci\u00f3 demasiado caro, as\u00ed que decid\u00ed hacer autoestop. <\/p>\n\n\n\n<p>Sin embargo, estaba lloviendo lo suyo y a\u00fan esper\u00e1ndome como una hora, no pas\u00f3 nadie, as\u00ed que decid\u00ed abortar la misi\u00f3n. Si vas en fin de semana probablemente tengas m\u00e1s suerte.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\">D\u00f3nde alojarse en Dohuk<\/h4>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Hotel econ\u00f3mico &#8211;<\/strong> <span style=\"text-decoration: underline;\">Parleman Hotel<\/span> &#8211; Hay varios hoteles alrededor del bazar pero ninguno puede reservarse online. Yo hice Couchsurfing, pero me dijeron que el Parleman Hotel est\u00e1 m\u00e1s o menos bien.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Mejor &#8211;<\/strong>&nbsp;<span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.booking.com\/hotel\/iq\/kristal.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\">Christal Hotel Dohuk<\/a><\/strong><\/span> &#8211; El hotel m\u00e1s concurrido y de mejor relaci\u00f3n calidad-precio.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/www.booking.com\/hotel\/iq\/kristal.es.html?aid=1232728&amp;label=iraqi_kurdistan_itinerary_es\" style=\"border-radius:11px;background-color:#0c3b7c\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><strong>M\u00edralo en Booking.com<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\"><strong>C\u00f3mo llegar a Dohuk<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Si quieres ir en taxi, los taxis compartidos cobran 6,000ID por persona desde Amedi. Si vienes de Erbil, hay veh\u00edculos a doquier, tanto autobuses como taxis.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-14506 size-full\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180422_162811.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180422_162811.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/IMG_20180422_162811.jpg\" alt class=\"wp-image-14506\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"color: #808080;\"><em><span style=\"font-size: 10pt;\">Dohuk<\/span><\/em><\/span><\/figcaption><\/figure>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"14\">D\u00eda 15 &#8211; Lalish<\/h3>\n\n\n\n<p>Res\u00e9rvate el \u00faltimo d\u00eda para visitar uno de los lugares m\u00e1s peculiares y emblem\u00e1ticos de Kurdist\u00e1n: Lalish<\/p>\n\n\n\n<p>Alguna vez has o\u00eddo hablar del Yazidismo?<\/p>\n\n\n\n<p>Los Yazidis son un grupo religioso que viven principalmente por Oriente Medio, el C\u00e1ucaso, Turqu\u00eda y <a href=\"https:\/\/againstthecompass.com\/es\/viajar-rusia\/\"><strong>Rusia<\/strong><\/a> pero la mayor parte viven en Irak.<\/p>\n\n\n\n<p>Son monote\u00edstas y su religi\u00f3n es una mezcla de zoroastranismo, islam, cristianismo y juda\u00edsmo. Es un poco complicado y no quiero adentrarme en detalles, aunque tampoco es que tenga mucha idea.<\/p>\n\n\n\n<p>Uno de los lugares m\u00e1s sagrados para los Yazidis es Lalish, una peque\u00f1a aldea del Kurdist\u00e1n iraqu\u00ed donde hay un templo muy sagrado.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14504\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/lalish.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/lalish.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/lalish.jpg\" alt class=\"wp-image-14504\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>El templo Yazidi<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<p>Lo primero que debes de saber sobre Lalish es que no se puede ir en zapatos, sino que hay que ir descalzo.<\/p>\n\n\n\n<p>En la entrada del pueblo, hay un control policial que te dice que te quites los zapatos inmediatamente.<\/p>\n\n\n\n<p>Sin embargo, Lalish no es como una de aquellas mezquitas con aquellos suelos tan blanditos.<\/p>\n\n\n\n<p>No.<\/p>\n\n\n\n<p>Es un pueblo y las calles de Lalish est\u00e1n sin asfaltar, llenas de piedras y adem\u00e1s est\u00e1 construido encima una colina.<\/p>\n\n\n\n<p>Los Yazidis tienen cosas muy curiosas. Por ejemplo, tienen un ritual muy antiguo que consiste en abrazar un \u00e1rbol (muy antiguo tambi\u00e9n) y, si consigues rodearlo por completo y tocarte los dedos, significa que encontrar\u00e1s el amor verdadero. Si no puedes, puede que est\u00e9s solo para siempre.<\/p>\n\n\n\n<p>Yo fui capaz de no solamente tocarme los dedos sino que puede agarrarme los manos y, supuestamente, esto significa que tendr\u00e9 4 o 5 mujeres a la vez. No s\u00e9, esto es lo que me dijeron.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00f3nde alojarse en Lalish<\/h4>\n\n\n\n<p>No hay hoteles. Yo vine aqu\u00ed desde Dohuk y volv\u00ed por la tarde.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">C\u00f3mo llegar a Lalish<\/h4>\n\n\n\n<p>Tampoco hay transporte p\u00fablico. Tendr\u00e1s que, por en\u00e9sima vez, hacer autoestop. Yo cog\u00ed un taxi hasta las afueras de Dohuk e hice autoestop desde la misma autopista. Por suerte, se pararon bien r\u00e1pido.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full wp-image-14496\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/yazidi-people.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/yazidi-people.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/yazidi-people.jpg\" alt class=\"wp-image-14496\"><\/picture><figcaption class=\"wp-element-caption\"><span style=\"font-size: 10pt; color: #808080;\"><em>Una mujer Yazidi<\/em><\/span><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"4\">M\u00e1s informaci\u00f3n para complementar tu ruta por Kurdist\u00e1n<\/h2>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-background\" style=\"background-color:#2b8f2b\">\ud83d\udce2 En la p\u00e1gina de <a href=\"https:\/\/againstthecompass.com\/es\/recursos-viajeros\/\"><strong>Recursos Viajeros<\/strong><\/a> pod\u00e9is encontrar la lista de todas las p\u00e1ginas y sitios que uso para reservar hoteles, tours, seguro de&nbsp;viaje&nbsp;y&nbsp;dem\u00e1s<\/p>\n\n\n\n<p>No te olvides de leer nuestra <a href=\"https:\/\/againstthecompass.com\/es\/viajar-irak-federal\/\"><strong>gu\u00edas de viaje a Irak<\/strong><\/a>.<\/p>\n\n\n\n<p>As\u00ed como todos nuestros art\u00edculos a Irak:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/againstthecompass.com\/es\/visita-mosul-tras-liberacion\/\">C\u00f3mo viajar a Mosul<\/a><\/span><\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/againstthecompass.com\/es\/campo-de-refugiados-sirio-iraq\/\">Visitando un campo de refugiados sirio en Irak<\/a><\/span><\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/againstthecompass.com\/es\/es-seguro-viajar-a-iraq\/\">Es Irak seguro para el turismo?<\/a><\/span><\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/againstthecompass.com\/es\/ruta-iraq-federal\/\">Ruta por Irak<\/a><\/span><\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/againstthecompass.com\/es\/10-cosas-que-hacer-en-erbil-iraq\/\">C\u00f3mo viajar a Erbil<\/a><\/span><\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/againstthecompass.com\/es\/viajar-kurdistan-iraqui-mujer\/\">Gu\u00eda para mujeres que viajan a Kurdistan Iraqui<\/a><\/span><\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/againstthecompass.com\/es\/viaje-amadiya-increible-kurdistan-iraqui\/\">Gu\u00edas de viaje a Amadiya<\/a><\/span><\/li>\n\n\n\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/againstthecompass.com\/es\/guia-viaje-kurdistan-iraqui\/\">Gu\u00edas de viaje a Kurdistan Iraqui<\/a><\/span><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><picture><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/ruta-kurdistan.avif\" type=\"image\/avif\"><source srcset=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/ruta-kurdistan.jpg\" type=\"image\/jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/againstthecompass.com\/wp-content\/uploads\/2018\/10\/ruta-kurdistan.jpg\" alt=\"ruta Kurdist\u00e1n\" class=\"wp-image-14532\" style=\"object-fit:cover;width:514px;height:auto\"><\/picture><\/figure>\n\n\n\n<p><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Y qu\u00e9 puedo&nbsp;decir sobre el Kurdist\u00e1n iraqu\u00ed que no haya mencionado ya? A pesar de ser una regi\u00f3n de lo m\u00e1s peque\u00f1a, localizada en pleno coraz\u00f3n de Oriente Medio, y a\u00fan perteneciendo a una pa\u00eds \u00e1rabe llamado Irak que lleva varias d\u00e9cadas en guerra, el Kurdist\u00e1n iraqu\u00ed es un pa\u00eds, o un lugar si lo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_wp_convertkit_post_meta":{"form":"6000233","landing_page":"","tag":"0","restrict_content":"0"},"footnotes":""},"categories":[163,159,155],"tags":[],"class_list":["post-14479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guias-de-viaje","category-iraq","category-oriente-medio"],"acf":[],"_links":{"self":[{"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/posts\/14479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/comments?post=14479"}],"version-history":[{"count":4,"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/posts\/14479\/revisions"}],"predecessor-version":[{"id":59120,"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/posts\/14479\/revisions\/59120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/media\/13840"}],"wp:attachment":[{"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/media?parent=14479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/categories?post=14479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/againstthecompass.com\/es\/wp-json\/wp\/v2\/tags?post=14479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}